{"id":702,"date":"2020-03-02T07:14:00","date_gmt":"2020-03-02T05:14:00","guid":{"rendered":"http:\/\/46.101.167.100\/?p=702"},"modified":"2020-02-22T09:16:03","modified_gmt":"2020-02-22T07:16:03","slug":"franquicia-mia-gelateria-individual-ice-cream-y-cross-entry","status":"publish","type":"post","link":"https:\/\/www.eis-macher.de\/es\/eisherstellung\/franchise-mia-gelateria-individuelles-eis-und-quereinstieg\/","title":{"rendered":"Franquicia Mia Gelateria - Helado individual y entrada lateral"},"content":{"rendered":"<p>En el sitio web de Messe Stuttgart para GELATISSIMO 2020, vi por primera vez el <strong>Concepto de franquicia <a href=\"https:\/\/www.mia-gelateria.com\/\" target=\"_blank\" rel=\"noopener\">Mia Gelateria<\/a><\/strong> lleg\u00f3 a conocer. Por desgracia, la empresa no estaba presente en GELATISSIMO, de lo contrario me habr\u00eda encantado probar el helado yo mismo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El concepto de franquicia Mia Gelateria<\/h2>\n\n\n\n<p>En 2014, Roman Schaller fund\u00f3 una <strong>Cadena de helader\u00edas con autoservicio<\/strong>. Hasta ahora, esta iniciativa es \u00fanica en Alemania. Ahora hay sucursales en Austria, Alemania, Suiza y Francia.<\/p>\n\n\n\n<p>As\u00ed que si est\u00e1s pensando en abrir una helader\u00eda, esta franquicia puede ser la adecuada para ti. Tambi\u00e9n <strong>Cambio de carrera<\/strong> son bienvenidos. El concepto est\u00e1 bien pensado y necesita <strong>S\u00f3lo unos pocos conocimientos b\u00e1sicos<\/strong>. La masa l\u00edquida de helado se suministra lista para usar y s\u00f3lo hay que introducirla en las m\u00e1quinas de helado.<\/p>\n\n\n\n<p>As\u00ed que si ahora le apetece abrir su propia helader\u00eda, eche un vistazo al <a href=\"https:\/\/franchise.mia-gelateria.com\/\" target=\"_blank\" rel=\"noopener\">Informaci\u00f3n sobre la empresa franquiciadora<\/a> an. Aqu\u00ed tambi\u00e9n puede ver r\u00e1pidamente en qu\u00e9 ciudades se buscan preferentemente socios.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Schaller.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Schaller.jpg\" alt=\" Roman Schaller hat 2014 das Franchise-Unternehmen Mia Gelateria gegr\u00fcndet(Foto: Messe Stuttgart , Bildnachweis Mia Gelateria) \" class=\"wp-image-705\" srcset=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Schaller.jpg 600w, https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Schaller-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" data-no-translation=\"\" \/><\/a><figcaption> Roman Schaller fund\u00f3 la empresa de franquicias Mia Gelateria en 2014<br>(Foto: Messe Stuttgart , cr\u00e9dito fotogr\u00e1fico Mia Gelateria) <\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Informaci\u00f3n sobre la oferta de helados <\/h2>\n\n\n\n<p>Seg\u00fan Roman Schaller, la base de helado se produce en Austria de acuerdo con <strong>receta original italiana<\/strong>. Encontrar\u00e1 <strong>Leche alpina y s\u00f3lo ingredientes naturales y de alta calidad<\/strong> \u00dasalo.<\/p>\n\n\n\n<p>Por consiguiente, aqu\u00ed no hay productos artificiales, como se utilizan en muchas otras helader\u00edas. Ya he escrito sobre esto en mi art\u00edculo <a href=\"https:\/\/www.eis-macher.de\/es\/produccion-de-helados\/9-consejos-para-reconocer-un-heladeria-buenisima\/\">\"9 consejos para reconocer una buena helader\u00eda\"<\/a> escrito.<\/p>\n\n\n\n<p>Lo m\u00e1s destacado del concepto Mia Gelateria es que cada comensal prepara su propio helado. Como en un <strong>Buffet <\/strong>est\u00e1n los diferentes <strong>Sabores y coberturas de helado <\/strong>para elegir. Las posibilidades de combinaci\u00f3n son, por tanto, casi ilimitadas.<\/p>\n\n\n\n<p>En <strong>Selecci\u00f3n de variedades <\/strong>abarca desde los cl\u00e1sicos como chocolate, fresa y vainilla hasta variedades m\u00e1s inusuales como pan de especias, menta, regaliz y mojito.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Toppings.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Toppings.jpg\" alt=\"Die Toppingauswahl bei Mia Gelateria - hier kann vom Eis \u00fcber das Topping alles selbst ausgesucht und kombiniert werden(Foto: Messe Stuttgart , Bildnachweis Mia Gelateria)\" class=\"wp-image-706\" srcset=\"https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Toppings.jpg 600w, https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Toppings-300x200.jpg 300w, https:\/\/www.eis-macher.de\/wp-content\/uploads\/2020\/02\/MiaGelateria-Messe-Stuttgart_Toppings-480x320.jpg 480w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" data-no-translation=\"\" \/><\/a><figcaption> La selecci\u00f3n de coberturas en Mia Gelateria: aqu\u00ed puedes elegir y combinar t\u00fa mismo desde el helado hasta las coberturas.<br>(Foto: Messe Stuttgart , cr\u00e9dito fotogr\u00e1fico Mia Gelateria) <\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Procedimiento para el cliente y fijaci\u00f3n de precios<\/h2>\n\n\n\n<p>Por desgracia, a\u00fan no hay sucursal en M\u00fanich, as\u00ed que s\u00f3lo puedo contarles lo que he le\u00eddo. El cliente se sirve en un mostrador. Primero puede elegir entre <strong>Variedades de helado que cambian a diario<\/strong>elegir las que m\u00e1s le gusten. Adem\u00e1s, hay una gran variedad de <strong>Salsas y aderezos<\/strong>para montar tu propia creaci\u00f3n. En el <strong>Pedido<\/strong> a continuaci\u00f3n se pesa la taza y se <strong>Precio<\/strong> \u00fanicamente sobre la base de la <strong>Peso total<\/strong> calculado.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Seg\u00fan la p\u00e1gina web, pronto se abrir\u00e1 una helader\u00eda en M\u00fanich. Cuando llegue el momento, por supuesto, se lo contaremos.<\/p>","protected":false},"excerpt":{"rendered":"<p>En Mia Gelateria, los clientes pueden montar su propio helado en el mostrador. Suena muy divertido y con grandes creaciones. Quien quiera abrir una helader\u00eda como cambio profesional tambi\u00e9n est\u00e1 aqu\u00ed en el lugar adecuado.<\/p>","protected":false},"author":2,"featured_media":706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[8],"tags":[19],"class_list":["post-702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eisherstellung","tag-eisdiele"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/posts\/702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/comments?post=702"}],"version-history":[{"count":0,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/posts\/702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/media\/706"}],"wp:attachment":[{"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/media?parent=702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/categories?post=702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eis-macher.de\/es\/wp-json\/wp\/v2\/tags?post=702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}